{"id":14837,"date":"2022-03-10T12:49:07","date_gmt":"2022-03-10T12:49:07","guid":{"rendered":"https:\/\/islashormigas.com\/?post_type=product&#038;p=14837"},"modified":"2024-07-23T10:09:08","modified_gmt":"2024-07-23T10:09:08","slug":"aowd-nitrox-padi","status":"publish","type":"product","link":"https:\/\/islashormigas.com\/pl\/curso\/aowd-nitrox-padi\/","title":{"rendered":"AOWD + NITROX PADI"},"content":{"rendered":"<p>El curso de AOWD cl\u00e1sico se compone de 5 inmersiones espec\u00edficas (Flotabilidad, Orientaci\u00f3n, Profunda, Pecio y Nitrox).<\/p>\n<p>Se obtiene la titulaci\u00f3n de AOWD.<\/p>\n<p>Se necesitan 3 d\u00edas.<\/p>\n<p>Durante este curso se ampliar\u00e1n los conocimientos adquiridos en el Open Water Diver, desarrollando t\u00e9cnicas y experiencias suplementarias en inmersiones espec\u00edficas con condiciones especiales. Es un curso de car\u00e1cter pr\u00e1ctico.<\/p>\n<p>Adem\u00e1s, si lo deseas, podr\u00e1s completar tu formaci\u00f3n a\u00f1adiendo la especialidad de Nitrox a tu titulaci\u00f3n de Advanced a un precio especial <i>(consultar tarifas<\/i>).<\/p>\n<p><b>Estructura:<\/b><\/p>\n<p>El programa del curso AOWD cl\u00e1sico consta de 5 inmersiones (6 si incluimos la especialidad de Nitrox):<\/p>\n<ul>\n<li>Flotabilidad<\/li>\n<li>Orientaci\u00f3n<\/li>\n<li>Profunda<\/li>\n<li>Pecio<\/li>\n<li>Nitrox 1\/ multinivel<\/li>\n<li>Nitrox 2 * (<i>incluyendo especialidad Nitrox<\/i>)<\/li>\n<\/ul>\n<p><b>Incluye:<\/b><\/p>\n<ul>\n<li>Manual del curso<\/li>\n<li>Clases te\u00f3ricas<\/li>\n<li>Tramitaci\u00f3n de titulaci\u00f3n<\/li>\n<li>Instructor cualificado con amplia experiencia<\/li>\n<\/ul>\n<p><b>Requisitos:<\/b><\/p>\n<ul>\n<li>Edad m\u00ednima 15 a\u00f1os<\/li>\n<li>Titulaci\u00f3n de OW o equivalente<\/li>\n<li>Seguro de buceo en vigor<\/li>\n<li>Fotograf\u00edas tama\u00f1o carnet<\/li>\n<li>Certificado m\u00e9dico en vigor<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El curso de AOWD cl\u00e1sico se compone de 5 inmersiones espec\u00edficas (Flotabilidad, Orientaci\u00f3n, Profunda, Pecio y Nitrox). Se obtiene la titulaci\u00f3n de AOWD. Se necesitan 3 d\u00edas. Durante este curso se ampliar\u00e1n los conocimientos adquiridos en el Open Water Diver, desarrollando t\u00e9cnicas y experiencias suplementarias en inmersiones espec\u00edficas con condiciones especiales. Es un curso de&#8230;<\/p>\n","protected":false},"featured_media":14193,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[105],"product_tag":[],"yst_prominent_words":[559,550,647,648,524,526,522,561,535,407,560,518,562,564,563,527,555],"class_list":["post-14837","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-avanzados","pa_certificacion-padi","pa_certificacion-ssi","pa_duracion-3-dias","pa_inmersiones-123"],"_links":{"self":[{"href":"https:\/\/islashormigas.com\/pl\/wp-json\/wp\/v2\/product\/14837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/islashormigas.com\/pl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/islashormigas.com\/pl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/islashormigas.com\/pl\/wp-json\/wp\/v2\/comments?post=14837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/islashormigas.com\/pl\/wp-json\/wp\/v2\/media\/14193"}],"wp:attachment":[{"href":"https:\/\/islashormigas.com\/pl\/wp-json\/wp\/v2\/media?parent=14837"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/islashormigas.com\/pl\/wp-json\/wp\/v2\/product_cat?post=14837"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/islashormigas.com\/pl\/wp-json\/wp\/v2\/product_tag?post=14837"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/islashormigas.com\/pl\/wp-json\/wp\/v2\/yst_prominent_words?post=14837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}